{"id":28633,"date":"2026-05-09T12:15:13","date_gmt":"2026-05-09T10:15:13","guid":{"rendered":"https:\/\/finelife.tv\/fr\/?p=28633"},"modified":"2026-05-13T09:48:45","modified_gmt":"2026-05-13T07:48:45","slug":"solaris-chambord-dun-solstice-a-lautre","status":"publish","type":"post","link":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/","title":{"rendered":"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1018\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22-1024x1018.jpeg\" alt=\"\" class=\"wp-image-28733\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22-1024x1018.jpeg 1024w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22-300x298.jpeg 300w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22-150x150.jpeg 150w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22-768x763.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22-1536x1526.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22-2048x2035.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre. Le photographe Robert Charles Mann pr\u00e9sente une quarantaine de photos st\u00e9nop\u00e9es qui gravent la m\u00e9moire du temps comme le font les cernes d\u2019un arbre. Entre gothique et Technicolor.<\/strong> <br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><br>Le Ch\u00e2teau de Chambord a le go\u00fbt des symboles. En 2022, le domaine invitait le plasticien Pablo Reinoso en r\u00e9sidence pendant trois mois  &#8230; dur\u00e9e du s\u00e9jour de Fran\u00e7ois 1er. En 2024, il s&rsquo;attache \u00e0 un autre temps : les solstices. Chambord convie le photographe Robert Charles Mann \u00e0 s\u00e9journer pendant six mois \u2013 du solstice d\u2019hiver 2024 (21 d\u00e9cembre) au solstice d\u2019\u00e9t\u00e9 2025 (21 juin). Ses 43 appareils st\u00e9nop\u00e9s artisanaux, pos\u00e9s sur les toits du ch\u00e2teau et dans la for\u00eat, ont laiss\u00e9 le soleil, les nuages, les brumes, les oiseaux et les arbres imprimer directement leurs traces sur du papier photosensible.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La solarigraphie : quand la lumi\u00e8re \u00e9crit le temps<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1008\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-expo22-1024x1008.jpeg\" alt=\"\" class=\"wp-image-28734\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-expo22-1024x1008.jpeg 1024w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-expo22-300x295.jpeg 300w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-expo22-768x756.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-expo22-1536x1513.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-expo22-2048x2017.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Vue de l&rsquo;exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<p><br>Pas de d\u00e9clencheur, pas d\u2019objectif, pas de montage : une unique exposition continue en solarigraphie, technique extr\u00eame de photographie st\u00e9nop\u00e9 (pinhole photography).<br>Robert Charles Mann con\u00e7oit lui-m\u00eame ses cam\u00e9ras \u00e0 partir de mat\u00e9riaux simples et souvent recycl\u00e9s. Il transforme des objets du quotidien en instruments po\u00e9tiques : bo\u00eetes de bonbons, bo\u00eetes de caf\u00e9, bo\u00eetes de whisky ou autres contenants m\u00e9talliques. Il perce un minuscule trou (le st\u00e9nop\u00e9) dans la bo\u00eete, place \u00e0 l\u2019int\u00e9rieur une feuille de papier photosensible argentique, puis scelle le tout de mani\u00e8re \u00e9tanche \u00e0 la lumi\u00e8re.<\/p>\n\n\n\n<p>Ces cam\u00e9ras rudimentaires, fix\u00e9es en hauteur ou dans la for\u00eat, sont orient\u00e9es vers le ciel. Pendant six mois entiers, elles capturent sans interruption le mouvement apparent du soleil. Chaque jour, le soleil trace un arc lumineux sur le papier. Au fil des saisons, ces arcs se superposent, cr\u00e9ant des courbes complexes qui enregistrent non seulement la course du soleil, mais aussi les variations de luminosit\u00e9, les passages nuageux, les brumes et m\u00eame le vol des oiseaux.<\/p>\n\n\n\n<p><br>Le r\u00e9sultat est une image unique, non composite, o\u00f9 le temps se grave litt\u00e9ralement : comme les cernes d\u2019un arbre qui portent la m\u00e9moire des saisons, des s\u00e9cheresses et des pluies. Chaque arc solaire condense une demi-ann\u00e9e de mouvement c\u00e9leste, chaque courbe devient une m\u00e9moire du ciel.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-pht-arcs-rouges-bleus22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28737\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-pht-arcs-rouges-bleus22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-pht-arcs-rouges-bleus22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-pht-arcs-rouges-bleus22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-pht-arcs-rouges-bleus22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-pht-arcs-rouges-bleus22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Vue de l&rsquo;exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><br>Une colorisation magistrale<\/h2>\n\n\n\n<p>De retour en studio, Robert Charles Mann scanne ces empreintes uniques et les sublime par une colorisation d\u00e9licate et ma\u00eetris\u00e9e \u2013 un geste qui demande \u00e0 la fois l\u2019\u0153il du photographe et la sensibilit\u00e9 de l\u2019artisan. <\/p>\n\n\n\n<p>Ancien collaborateur d\u2019Hollywood et tireur pour les plus grands photographes am\u00e9ricains (Herb Ritts dont il a dirig\u00e9 le studio pendant deux ans, Helmut Newton, Mary Ellen Mark, Peter Lindbergh, Dennis Hopper\u2026), il transforme ces documents cosmiques en visions po\u00e9tiques. Depuis 2008, Robert Charles Mann travaille \u00e9galement comme tireur photo personnel de Brad Pitt. C\u2019est d\u2019ailleurs dans ce sillage qu\u2019il a compos\u00e9 plusieurs musiques de films, dont The Aerialist et Espions, nomm\u00e9 au C\u00e9sar du Meilleur Premier Film, et a collabor\u00e9 \u00e0 la BO d&rsquo;Ad Astra avec Brad Pitt, nomm\u00e9 aux Grammy Awards.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Les arcs de couleurs : une palette entre science et po\u00e9sie<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-jaunes22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28736\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-jaunes22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-jaunes22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-jaunes22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-jaunes22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-jaunes22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Vue de l&rsquo;exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<p><br>Les couleurs qui apparaissent ne sont pas celles du ciel au moment de la prise de vue, mais le r\u00e9sultat des r\u00e9actions chimiques du papier expos\u00e9 de mani\u00e8re extr\u00eame (solarisation, humidit\u00e9, variations de temp\u00e9rature).<\/p>\n\n\n\n<p>Les tons chauds (variations intenses autour du rouge, orange et dor\u00e9) \u00e9voquent souvent l\u2019\u00e9nergie, la lumi\u00e8re puissante et les p\u00e9riodes les plus ensoleill\u00e9es. Ils donnent une dimension presque sacr\u00e9e ou incandescente aux arcs, comme un feu c\u00e9leste.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-arcs-bleus22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28735\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-arcs-bleus22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-arcs-bleus22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-arcs-bleus22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-arcs-bleus22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-arcs-bleus22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Vue exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Les tons froids (bleus profonds, bleu magenta cristallin, mauve, cobalt) apportent une dimension spectrale, gothique et contemplative. Ils traduisent les p\u00e9riodes plus douces ou brumeuses, les jours nuageux, ou les moments o\u00f9 la lumi\u00e8re est plus diffuse. Le bleu magenta en majest\u00e9 cr\u00e9e une atmosph\u00e8re myst\u00e9rieuse et cosmique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un Chambord spectral et intemporel<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-bleus22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28741\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-bleus22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-bleus22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-bleus22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-bleus22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-photo-arcs-bleus22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Vue de l&rsquo;exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<p>\u00c0 l&rsquo;int\u00e9rieur du ch\u00e2teau, l&rsquo;exposition baigne dans une musique originale compos\u00e9e par le photographe. Une partition qui \u00e9volue sans cesse en \u00e9cho aux mouvements des astres qui se retrouvent dans les arcs des solarigraphies. Une fa\u00e7on de prolonger le vertige temporel au-del\u00e0 de l&rsquo;image.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-charles-Mann-dans-domaine22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28738\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-charles-Mann-dans-domaine22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-charles-Mann-dans-domaine22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-charles-Mann-dans-domaine22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-charles-Mann-dans-domaine22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-charles-Mann-dans-domaine22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Robert Charles Mann dans la for\u00eat de Chambord<\/figcaption><\/figure>\n<\/div>\n\n\n<p>R\u00e9sultat : des images spectaculaires, parfois gothiques et spectrales, toujours profond\u00e9ment abstraites et atmosph\u00e9riques. Mais aussi des \u0153uvres en dialogue avec celles d\u2019anciens r\u00e9sidents. Comme cette grande chouette de Lionel Sabatt\u00e9 pos\u00e9e comme une \u00e9vidence pr\u00e8s d\u2019un \u00e9tang. Une autre vigile du temps. D\u2019un temps beaucoup plus lointain. Le sculpteur aurait d\u00e9couvert un petit ossement de dinosaure alors qu\u2019il travaillait \u00e0 sa Chouette selon la l\u00e9gende de l&rsquo;atelier. <br><\/p>\n\n\n\n<p>L&rsquo;exposition Solaris est une m\u00e9ditation visuelle sur le temps, la lumi\u00e8re et la nature. Chambord r\u00e9invent\u00e9, hant\u00e9 par le temps qui passe, comme si le ch\u00e2teau lui-m\u00eame portait les marques invisibles des si\u00e8cles. \u00c0 voir absolument !<\/p>\n\n\n\n<p>Pour prolonger l&rsquo;exp\u00e9rience, le catalogue de l&rsquo;exposition, <em>Solargraphs <\/em>est publi\u00e9 par Hemeria et disponible \u00e0 59 euros<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">INFOS<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-chateau22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28739\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-chateau22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-chateau22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-chateau22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-chateau22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre-vue-chateau22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n<p><br><strong>Exposition SOLARIS<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Robert Charles Mann <\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.chambord.org\/fr\/\">Domaine national de Chambord<\/a><\/strong> au deuxi\u00e8me \u00e9tage <br>Jusqu&rsquo;au 21 juin 2026 <\/p>\n\n\n\n<p>Coproduite par la galerie Capazza<\/p>\n\n\n\n<p>L\u2019exposition est comprise dans le billet d\u2019entr\u00e9e : plein tarif 21 \u20ac ; tarif r\u00e9duit 18,50 \u20ac ; gratuit pour les moins de 18 ans et pour les moins de 26 ans ressortissants de l\u2019Union Europ\u00e9enne.<\/p>\n\n\n\n<p>Horaires d\u2019ouverture :<br>\u2013 du 20 au 27 mars : 9h \u2013 17h ;<br>\u2013 du 28 mars au 21 juin : 9h \u2013 18h.<\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<p>Article li\u00e9 \u00e0 <strong>Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre<\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/finelife.tv\/fr\/2022\/07\/19\/chambord-pablo-reinoso-et-l-art-des-debordements\/\">Chambord : Pablo Reinoso et l\u2019art des d\u00e9bordements<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre. Le photographe Robert Charles Mann pr\u00e9sente une quarantaine de photos stenop\u00e9es qui gravent la m\u00e9moire du temps comme le font les cernes d\u2019un arbre. Entre gothique et Technicolor.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[3557,6200,6202,6204,168,5983,5982,6203],"class_list":["post-28633","post","type-post","status-publish","format-standard","hentry","category-blog","tag-chambord","tag-chateau-et-domaine-chambord","tag-exposition-chambord","tag-photo-traditionnelle","tag-photographie","tag-robert-charles-mann","tag-solaris","tag-stenope"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre - FineLife.tv<\/title>\n<meta name=\"description\" content=\"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre. Le photographe Robert Charles Mann pr\u00e9sente une quarantaine de photos stenop\u00e9es qui gravent la m\u00e9moire du temps comme le font les cernes d\u2019un arbre. Entre gothique et Technicolor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre - FineLife.tv\" \/>\n<meta property=\"og:description\" content=\"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre. Le photographe Robert Charles Mann pr\u00e9sente une quarantaine de photos stenop\u00e9es qui gravent la m\u00e9moire du temps comme le font les cernes d\u2019un arbre. Entre gothique et Technicolor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/\" \/>\n<meta property=\"og:site_name\" content=\"FineLife.tv\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-09T10:15:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T07:48:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2396\" \/>\n\t<meta property=\"og:image:height\" content=\"2381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@finelifetv\" \/>\n<meta name=\"twitter:site\" content=\"@finelifetv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/\"},\"author\":{\"name\":\"Leonore\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#\\\/schema\\\/person\\\/e3d980b0c0b3dc5af01c3455893c8c52\"},\"headline\":\"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre\",\"datePublished\":\"2026-05-09T10:15:13+00:00\",\"dateModified\":\"2026-05-13T07:48:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/\"},\"wordCount\":996,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22-1024x1018.jpeg\",\"keywords\":[\"Chambord\",\"chateau et domaine chambord\",\"exposition Chambord\",\"photo traditionnelle\",\"photographie\",\"robert charles mann\",\"solaris\",\"stenope\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/\",\"url\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/\",\"name\":\"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre - FineLife.tv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22-1024x1018.jpeg\",\"datePublished\":\"2026-05-09T10:15:13+00:00\",\"dateModified\":\"2026-05-13T07:48:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#\\\/schema\\\/person\\\/e3d980b0c0b3dc5af01c3455893c8c52\"},\"description\":\"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre. Le photographe Robert Charles Mann pr\u00e9sente une quarantaine de photos stenop\u00e9es qui gravent la m\u00e9moire du temps comme le font les cernes d\u2019un arbre. Entre gothique et Technicolor.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22.jpeg\",\"contentUrl\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22.jpeg\",\"width\":2396,\"height\":2381},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/09\\\/solaris-chambord-dun-solstice-a-lautre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/\",\"name\":\"FineLife.tv\",\"description\":\"Quand l&#039;Art de vivre croise l&#039;Art de penser\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#\\\/schema\\\/person\\\/e3d980b0c0b3dc5af01c3455893c8c52\",\"name\":\"Leonore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g\",\"caption\":\"Leonore\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre - FineLife.tv","description":"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre. Le photographe Robert Charles Mann pr\u00e9sente une quarantaine de photos stenop\u00e9es qui gravent la m\u00e9moire du temps comme le font les cernes d\u2019un arbre. Entre gothique et Technicolor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/","og_locale":"fr_FR","og_type":"article","og_title":"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre - FineLife.tv","og_description":"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre. Le photographe Robert Charles Mann pr\u00e9sente une quarantaine de photos stenop\u00e9es qui gravent la m\u00e9moire du temps comme le font les cernes d\u2019un arbre. Entre gothique et Technicolor.","og_url":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/","og_site_name":"FineLife.tv","article_published_time":"2026-05-09T10:15:13+00:00","article_modified_time":"2026-05-13T07:48:45+00:00","og_image":[{"width":2396,"height":2381,"url":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22.jpeg","type":"image\/jpeg"}],"author":"Leonore","twitter_card":"summary_large_image","twitter_creator":"@finelifetv","twitter_site":"@finelifetv","twitter_misc":{"\u00c9crit par":"Leonore","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/#article","isPartOf":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/"},"author":{"name":"Leonore","@id":"https:\/\/finelife.tv\/fr\/#\/schema\/person\/e3d980b0c0b3dc5af01c3455893c8c52"},"headline":"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre","datePublished":"2026-05-09T10:15:13+00:00","dateModified":"2026-05-13T07:48:45+00:00","mainEntityOfPage":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/"},"wordCount":996,"commentCount":0,"image":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/#primaryimage"},"thumbnailUrl":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22-1024x1018.jpeg","keywords":["Chambord","chateau et domaine chambord","exposition Chambord","photo traditionnelle","photographie","robert charles mann","solaris","stenope"],"articleSection":["Blog"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/","url":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/","name":"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre - FineLife.tv","isPartOf":{"@id":"https:\/\/finelife.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/#primaryimage"},"image":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/#primaryimage"},"thumbnailUrl":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22-1024x1018.jpeg","datePublished":"2026-05-09T10:15:13+00:00","dateModified":"2026-05-13T07:48:45+00:00","author":{"@id":"https:\/\/finelife.tv\/fr\/#\/schema\/person\/e3d980b0c0b3dc5af01c3455893c8c52"},"description":"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre. Le photographe Robert Charles Mann pr\u00e9sente une quarantaine de photos stenop\u00e9es qui gravent la m\u00e9moire du temps comme le font les cernes d\u2019un arbre. Entre gothique et Technicolor.","breadcrumb":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/#primaryimage","url":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22.jpeg","contentUrl":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Solaris-Chambord-d-un-solstice-a-l-autre22.jpeg","width":2396,"height":2381},{"@type":"BreadcrumbList","@id":"https:\/\/finelife.tv\/fr\/2026\/05\/09\/solaris-chambord-dun-solstice-a-lautre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/finelife.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"Solaris : Chambord d\u2019un solstice \u00e0 l\u2019autre"}]},{"@type":"WebSite","@id":"https:\/\/finelife.tv\/fr\/#website","url":"https:\/\/finelife.tv\/fr\/","name":"FineLife.tv","description":"Quand l&#039;Art de vivre croise l&#039;Art de penser","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/finelife.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/finelife.tv\/fr\/#\/schema\/person\/e3d980b0c0b3dc5af01c3455893c8c52","name":"Leonore","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g","caption":"Leonore"}}]}},"_links":{"self":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts\/28633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/comments?post=28633"}],"version-history":[{"count":27,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts\/28633\/revisions"}],"predecessor-version":[{"id":28862,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts\/28633\/revisions\/28862"}],"wp:attachment":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/media?parent=28633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/categories?post=28633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/tags?post=28633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}