{"id":28638,"date":"2026-05-08T20:02:43","date_gmt":"2026-05-08T18:02:43","guid":{"rendered":"https:\/\/finelife.tv\/fr\/?p=28638"},"modified":"2026-05-09T10:40:48","modified_gmt":"2026-05-09T08:40:48","slug":"lille-terre-de-femmes-et-de-haute-tapisserie","status":"publish","type":"post","link":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/","title":{"rendered":"Lille : terre de femmes et de haute tapisserie"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28665\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>Lille : terre de femmes et de haute tapisserie. L&rsquo;exposition <em>Tr\u00e9sors de laine et de soie<\/em> au mus\u00e9e de l&rsquo;Hospice Comtesse pr\u00e9sente pour la premi\u00e8re fois 11 tapisseries, monumentales et m\u00e9connues, de la manufacture Guillaume Werniers &amp; Catherine Ghuys. Verdures, portraits de cour, sc\u00e8nes sacr\u00e9es, autant d&rsquo;\u0153uvres de fils aux allures de tissu ou de peinture qui plongent dans l&rsquo;histoire de l&rsquo;Europe du Nord, de la haute lisse et du matrimoine.<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"849\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-musee-hospice-comtesse-lille22-849x1024.jpeg\" alt=\"\" class=\"wp-image-28666\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-musee-hospice-comtesse-lille22-849x1024.jpeg 849w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-musee-hospice-comtesse-lille22-249x300.jpeg 249w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-musee-hospice-comtesse-lille22-768x926.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-musee-hospice-comtesse-lille22-1274x1536.jpeg 1274w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-musee-hospice-comtesse-lille22-1698x2048.jpeg 1698w\" sizes=\"auto, (max-width: 849px) 100vw, 849px\" \/><figcaption class=\"wp-element-caption\">Vue entr\u00e9e du mus\u00e9e Hospice Comtesse<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Il y a comme un cheminement. Longer un mur de briques et de pierres jaune et rouge ponctu\u00e9 d\u2019arcades et de fen\u00eatres, puis franchir le porche aux portes de bois massif et traverser la cour pav\u00e9e. Enfin, laisser les yeux s\u2019habituer \u00e0 la demi p\u00e9nombre de l&rsquo;oratoire. Ce que l\u2019on voit alors, suspendu dans la premi\u00e8re salle de l\u2019Hospice Comtesse, ressemble \u00e0 deux portes ouvrant un univers textile raffin\u00e9, celui de la manufacture lilloise Guillaume Werniers &amp; Catherine Ghuys au XVIIIe si\u00e8cle.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-famille22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28686\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-famille22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-famille22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-famille22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-famille22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-famille22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Beaudoin de Constantinople, sa femme Marie et leurs filles Jeanne et Marguerite, vue de l&rsquo;exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<p>D\u2019un c\u00f4t\u00e9, la famille de Jeanne de Constantinople, future comtesse de Flandres. On la d\u00e9couvre, petite silhouette aux pieds de son p\u00e8re Baudouin et sa m\u00e8re Marie, sa s\u0153ur Marguerite \u00e0 ses c\u00f4t\u00e9s. De l\u2019autre, \u00e9galement une sc\u00e8ne de cour : Jeanne, entre ses deux maris, Ferdinand de Portugal et Thomas de Savoie. M\u00eame densit\u00e9, m\u00eame solennit\u00e9. Mais au-del\u00e0 de la majest\u00e9, on est saisi par la vie qui se d\u00e9gage de ces \u0153uvres, comme d&rsquo;ailleurs des onze tapisseries monumentales pr\u00e9sent\u00e9es.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-ses-deux-maris22-709x1024.jpeg\" alt=\"\" class=\"wp-image-28672\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-ses-deux-maris22-709x1024.jpeg 709w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-ses-deux-maris22-208x300.jpeg 208w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-ses-deux-maris22-768x1109.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-ses-deux-maris22-1063x1536.jpeg 1063w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-ses-deux-maris22-1418x2048.jpeg 1418w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-jeanne-de-flandres-et-ses-deux-maris22-scaled.jpeg 1772w\" sizes=\"auto, (max-width: 709px) 100vw, 709px\" \/><figcaption class=\"wp-element-caption\">Jeanne, entre ses deux maris, Ferdinand de Portugal et Thomas de Savoie, vue de l&rsquo;exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Des tr\u00e9sors \u00e0 la fabrication complexe <\/h2>\n\n\n\n<p><br>L\u2019exposition <em>Tr\u00e9sors de laine et de soie<\/em> d\u00e9voile litt\u00e9ralement des tr\u00e9sors. En effet, ces tapisseries, d\u2019une extr\u00eame fragilit\u00e9 en raison de leur poids et de leur grande sensibilit\u00e9 \u00e0 la lumi\u00e8re ne sortent que rarement de leur r\u00e9serve. De plus, \u00ab\u00a0Les tapisseries \u00e9taient des objets de prestige pris\u00e9s par les aristocrates, la haute bourgeoisie et les institutions religieuses\u00a0\u00bb rappelle H\u00e9l\u00e8ne Lobir charg\u00e9e de collections au Mus\u00e9e de l\u2019Hospice Comtesse. \u00ab\u00a0Aujourd&rsquo;hui, on pourrait les comparer \u00e0 une robe de haute couture ou une voiture de luxe\u00a0\u00bb. \u00c0 cheval entre l&rsquo;objet d&rsquo;art et l&rsquo;image, la tapisserie suivait un processus de fabrication complexe. \u00ab\u00a0Il fallait en g\u00e9n\u00e9ral un mois \u00e0 un tisseur pour r\u00e9aliser un m\u00e8tre carr\u00e9 mais ici, certaines tapisseries rassemblent le savoir et l&rsquo;\u00e9nergie de trois hommes\/femmes pendant le m\u00eame laps de temps\u00a0\u00bb pr\u00e9cise l&rsquo;attach\u00e9e de collection.<\/p>\n\n\n\n<p>P\u00e9dagogique, l&rsquo;exposition s&rsquo;attache aux techniques de fabrication de la manufacture Guillaume Werniers &amp; Catherine Ghuys au XVIIIe si\u00e8cle. \u00c0 l&rsquo;entr\u00e9e des cordes de laine teinte donnent le ton. Les couleurs tr\u00e8s pr\u00e9cises et vivantes des tapisseries r\u00e9sultent de savants m\u00e9langes de pigments. Plus loin, un m\u00e9tier \u00e0 tisser, des documents graphiques. Plus loin encore, des ateliers d&rsquo;initiation au tissage. Une trentaine d&rsquo;\u0153uvres dialoguent avec les tapisseries pour mieux comprendre le processus de fabrication : du prosa\u00efque livre de compte \u00e0 la c\u00e9ramique d\u00e9licate en passant par le jeu complexe des fuseaux. On comprend le geste, on comprend le temps.<\/p>\n\n\n\n<p>Il a fallu quatre ans de restauration pour redonner \u00e0 ces \u00e9toffes leur premier souffle. Une vid\u00e9o montre le travail d\u00e9licat de nettoyage, d\u00e9poussi\u00e9rage &#8230; effectu\u00e9 par de la Manufacture royale de Witt (Malines, Belgique). Un r\u00e9sultat saisissant : les couleurs ont la profondeur et la pr\u00e9cision d\u2019une peinture \u00e0 l\u2019huile. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La Bible et les T\u00e9ni\u00e8res : sacr\u00e9 et nature en laine et soie<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-christ-centurier-detail22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28668\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-christ-centurier-detail22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-christ-centurier-detail22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-christ-centurier-detail22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-christ-centurier-detail22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-christ-centurier-detail22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Le Christ et le Centurier, d\u00e9tail, vue de l&rsquo;exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<p>C&rsquo;est vrai pour les portraits de la haute noblesse comme pour les sc\u00e8nes sacr\u00e9es. En avan\u00e7ant dans l\u2019enfilade des salles, on d\u00e9couvre quatre tapisseries religieuses tiss\u00e9es entre 1735 et 1737 par Guillaume Werniers. L&rsquo;ensemble repr\u00e9sente des actions tir\u00e9es de la vie du Christ, des sc\u00e8nes de pr\u00e9dication et des miracles. Il a \u00e9t\u00e9 ex\u00e9cut\u00e9 \u00e0 partir des tableaux du peintre lillois Bernard-Joseph Wamps (1689-1744). <\/p>\n\n\n\n<p>La pi\u00e8ce ma\u00eetresse est sans doute <em>Le Christ et le Centurier<\/em> (photo d&rsquo;ouverture). La composition joue sur le contraste entre les couleurs douces et claires de la tenue du Christ \u00e0 la t\u00eate aur\u00e9ol\u00e9e d&rsquo;or et celles, sombres, du paysage. Elle se concentre par ailleurs sur des jeux de mains : celles du centurier et du Christ qui se touchent presque, mais aussi celles d&rsquo;un enfant qui, comme le regard, se tendent vers le ciel.<\/p>\n\n\n\n<p>La pr\u00e9cision des traits, l&rsquo;expressivit\u00e9 des visages sont impressionnantes comme l&rsquo;est le rendu des tissus (drap\u00e9s, camisoles) tout en fluidit\u00e9 et parfois en transparence. Les \u00ab\u00a0incarnations\u00a0\u00bb (les chairs, ou carnations parties les plus difficiles \u00e0 traiter) sont aussi particuli\u00e8rement r\u00e9ussies.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">T\u00e9ni\u00e8res : sc\u00e8nes champ\u00eatres<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"838\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-repos-des-bergers22-838x1024.jpeg\" alt=\"\" class=\"wp-image-28675\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-repos-des-bergers22-838x1024.jpeg 838w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-repos-des-bergers22-246x300.jpeg 246w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-repos-des-bergers22-768x938.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-repos-des-bergers22-1257x1536.jpeg 1257w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-repos-des-bergers22-1676x2048.jpeg 1676w\" sizes=\"auto, (max-width: 838px) 100vw, 838px\" \/><figcaption class=\"wp-element-caption\">Le repos des bergers, vue de l&rsquo;exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<p>On quitte le sacr\u00e9 pour plonger dans les T\u00e9ni\u00e8res : ces sc\u00e8nes de genre inspir\u00e9es du peintre flamand David Teniers II (1610-1690), sp\u00e9cialit\u00e9 de la manufacture Werniers. Paysans qui boivent et dansent, bergers dans des verdures anim\u00e9es, f\u00eates champ\u00eatres, moissons\u2026 <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-joueurs-de-cartes-detail22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28674\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-joueurs-de-cartes-detail22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-joueurs-de-cartes-detail22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-joueurs-de-cartes-detail22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-joueurs-de-cartes-detail22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-joueurs-de-cartes-detail22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Les joueurs de cartes, d\u00e9tail, vue de l&rsquo;exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<p>On est loin de la solennit\u00e9. \u00ab\u00a0C&rsquo;est une immersion dans la verdure et l&rsquo;oxyg\u00e8ne avec une foule de d\u00e9tails, notamment des animaux cach\u00e9s\u00a0\u00bb note H\u00e9l\u00e8ne Lobir. L\u2019atmosph\u00e8re est chaude, souvent joyeuse, avec \u00e7\u00e0 et l\u00e0, si l\u2019on regarde bien, une petite coquinerie discr\u00e8te dans les buissons \u2014 un regard, un geste \u2014 typique de l\u2019humour populaire flamand. Les bordures reprennent les motifs classiques de fleurs et de v\u00e9g\u00e9taux m\u00eal\u00e9s \u00e0 des troph\u00e9es agrestes, du gibier et des instruments de musique. Une sophistication qui semble r\u00e9interpr\u00e9ter l&rsquo;h\u00e9ritage de Charles V en mati\u00e8re de bordure. Ces motifs que l&rsquo;on trouve dans les tapisseries de cour : v\u00e9g\u00e9taux stylis\u00e9s, aigle symbole de vigilance, p\u00e9lican symbole du Christ et de puret\u00e9, &#8230;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-bergeres-laitieres22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28669\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-bergeres-laitieres22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-bergeres-laitieres22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-bergeres-laitieres22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-bergeres-laitieres22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-tenieres-bergeres-laitieres22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Laiti\u00e8res et berg\u00e8res, d\u00e9tail, vue de l&rsquo;exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Matrimoine : de Jeanne de Flandres \u00e0 Catherine Ghuys<\/h2>\n\n\n\n<p>L&rsquo;exposition parle aussi de matrimoine. Celui d&rsquo;une aristocrate, Jeanne de Flandres, et celui d&rsquo;une tapissi\u00e8re, Catherine Ghuys. <\/p>\n\n\n\n<p>Catherine Ghuys est la veuve de Guillaume Werniers (avant 1688-1738). Origine de Bruxelles, il reprend en 1701 la manufacture que son beau-p\u00e8re, Jean De Meltrer, avait fond\u00e9 \u00e0 Lille une douzaine d&rsquo;ann\u00e9es plus t\u00f4t. L&rsquo;atelier se sp\u00e9cialise dans les sc\u00e8nes de genre tr\u00e8s appr\u00e9ci\u00e9s par sa riche client\u00e8le internationale. Les tapisseries de pr\u00e8s de trois m\u00e8tres de haut r\u00e9chauffent les pi\u00e8ces tandis que les t\u00e9ni\u00e8res divertissent leurs propri\u00e9taires.<\/p>\n\n\n\n<p>\u00c0 la mort de Guillaume Werniers, Catherine Ghuys doit travailler avec le successeur d\u00e9sign\u00e9, Pierre Pannemaker. Mais elle s&rsquo;affranchit et dirige pendant quarante ans, jusqu&rsquo;\u00e0 sa mort en 1778, l\u2019atelier de 50 personnes. \u00ab La Veuve de G. Werniers \u00bb, maintient un niveau d\u2019excellence qui lui vaut une client\u00e8le allant des \u00c9tats de Flandre aux couvents, en passant par l\u2019aristocratie europ\u00e9enne.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Hospice Comtesse : terre matrimoniale <\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-detail-jeanne-de-flandre22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28671\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-detail-jeanne-de-flandre22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-detail-jeanne-de-flandre22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-detail-jeanne-de-flandre22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-detail-jeanne-de-flandre22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-detail-jeanne-de-flandre22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Jeanne de Flandres avec sa s\u0153ur Marguerite, son p\u00e8re Beaudoin et sa m\u00e8re Marie, vue de l&rsquo;exposition<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Si l\u2019exposition c\u00e9l\u00e8bre Catherine Ghuys, elle s\u2019inscrit dans une histoire plus longue, celle du mus\u00e9e lui-m\u00eame. L\u2019Hospice Comtesse a \u00e9t\u00e9 fond\u00e9 en 1237 par Jeanne de Constantinople \u2014 cette m\u00eame Jeanne dont les tapisseries vous accueillent d\u00e8s l\u2019entr\u00e9e. Comtesse de Flandre et de Hainaut, elle gouverne seule, fonde, b\u00e2tit, r\u00e9siste. Quand un imposteur pr\u00e9tend \u00eatre son p\u00e8re Baudouin, disparu lors de la quatri\u00e8me croisade, elle ne c\u00e8de pas \u00e0 la force mais joue la finesse : enqu\u00eates, confrontations, d\u00e9mystification publique. L\u2019imposteur est d\u00e9masqu\u00e9, arr\u00eat\u00e9, ex\u00e9cut\u00e9. Jeanne r\u00e8gne.<br><\/p>\n\n\n\n<p>Cinq si\u00e8cles s\u00e9parent Jeanne de Catherine. M\u00eame solitude au sommet, m\u00eame d\u00e9termination tranquille, m\u00eame refus de dispara\u00eetre derri\u00e8re un nom d\u2019homme. Le matrimoine, cet h\u00e9ritage transmis par les femmes, n\u2019est pas ici un concept militant. C\u2019est simplement ce que l\u2019histoire a laiss\u00e9 sur les murs.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le dialogue avec Teniers<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-palais-beaux-arts-lille22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28667\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-palais-beaux-arts-lille22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-palais-beaux-arts-lille22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-palais-beaux-arts-lille22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-palais-beaux-arts-lille22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-palais-beaux-arts-lille22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Palais des Beaux-Arts<\/figcaption><\/figure>\n<\/div>\n\n\n<p>L&rsquo;hospice Comtesse se situe dans le c\u0153ur historique de Lille. Pour d\u00e9couvrir les tr\u00e9sors architecturaux de la ville il faut faire un d\u00e9tour par le Palais des Beaux-Arts, \u00e0 quelques minutes \u00e0 pied. Ses collections rec\u00e8lent des tableaux de Teniers ou de son entourage, ceux-l\u00e0 m\u00eames qui ont servi de mod\u00e8les aux cartons ( dessins pr\u00e9paratoires) des tapissiers lillois. Voir les deux ensembles, c\u2019est comprendre une cha\u00eene de cr\u00e9ation : de la toile au fil, de la peinture \u00e0 la laine, d\u2019un atelier d\u2019Anvers \u00e0 une manufacture de Lille. Le m\u00eame paysan ivre, reproduit \u00e0 3 m\u00e8tres de hauteur, pour orner le mur d\u2019un couvent. Il y a l\u00e0 quelque chose de savoureusement d\u00e9cal\u00e9.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pause flamande<\/h2>\n\n\n\n<p>Entre les deux mus\u00e9es, une halte s\u2019impose rue de la Monnaie, chez Aux Merveilleux de Fred : gaufres fines et fondantes, vanille, vergeoise, sp\u00e9culoos ou pistache, modernes et r\u00e9confortantes. Pour accompagner, une bi\u00e8re craft locale chez C\u00e9lestin, tout proche rue Esquermoise. Le Nord dans un verre et dans une bouch\u00e9e.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>L&rsquo;art textile a le vent en poupe gr\u00e2ce au travail de pionni\u00e8res comme Olga de Amaral (voir notre article <strong><a href=\"https:\/\/finelife.tv\/fr\/2024\/11\/27\/expo-olga-de-amaral-lame-du-fiber-art\/\">Expo Olga de Amaral l\u2019\u00e2me du Fiber Art<\/a><\/strong>), Magdalena Abakanowicz et plus g\u00e9n\u00e9ralement aujourd&rsquo;hui gr\u00e2ce \u00e0 l&rsquo;exposition des \u0153uvres du Sud global. <em>Tr\u00e9sors de laine et de soie<\/em>, exposition discr\u00e8te mais qualitative,  pose un autre regard sur la cr\u00e9ation textile, et rappelle tout le savoir-faire et la po\u00e9sie de cet artisanat d\u2019art lillois.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">INFOS<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-hospice-cour22-768x1024.jpeg\" alt=\"\" class=\"wp-image-28687\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-hospice-cour22-768x1024.jpeg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-hospice-cour22-225x300.jpeg 225w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-hospice-cour22-1152x1536.jpeg 1152w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-hospice-cour22-1536x2048.jpeg 1536w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie-hospice-cour22-scaled.jpeg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\">Mus\u00e9e de l&rsquo;Hospice Comtesse<\/figcaption><\/figure>\n<\/div>\n\n\n<p><strong><em>Tr\u00e9sors de laine et de soie<\/em> les tapisseries <strong>de la manufacture Guillaume Werniers &amp; Catherine Ghuys au XVIIIe si\u00e8cle. <\/strong><\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/mhc.lille.fr\/\">Mus\u00e9e de l&rsquo;Hospice Comtesse<\/a> <\/strong><\/p>\n\n\n\n<p><strong>32 rue de la Monnaie<br>59000 LILLE<\/strong> <\/p>\n\n\n\n<p>Jusqu\u2019au 11 octobre 2026 <\/p>\n\n\n\n<p>Article li\u00e9 \u00e0 <strong>Lille : terre de femmes et de haute tapisserie<\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/finelife.tv\/fr\/2024\/10\/18\/expo-oudry-pose-ses-cartons-de-chasse-a-fontainebleau\/\">Expo Oudry pose ses cartons de chasse \u00e0 Fontainebleau<\/a><\/strong><br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;exposition Tr\u00e9sors de laine et de soie au mus\u00e9e de l&rsquo;Hospice Comtesse pr\u00e9sente 11 tapisseries m\u00e9connues de la manufacture Guillaume Werniers &#038; Catherine Ghuys. Verdures, sc\u00e8nes sacr\u00e9es et de cour, des chefs-d&rsquo;\u0153uvres de fils aux allures de peinture.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[6191,6199,6185,6192,6183,6182,6198,6190,6184,6196,6195,6197,6189,6188,6194,6193,6187,6186],"class_list":["post-28638","post","type-post","status-publish","format-standard","hentry","category-blog","tag-catherine-ghuys","tag-exposition-hospice-comtesse","tag-exposition-tresirs-de-laine-et-de-soie","tag-guillaume-werniers","tag-haute-lisse","tag-haute-tapisserie","tag-hospice-comtesse","tag-jeanne-de-flandres","tag-lille","tag-manufacture-wernieers-catherine-ghuys","tag-manufactures-du-nord-de-la-france","tag-matrimoine","tag-scene-champetres","tag-scenes-de-genre","tag-tapisserie-du-nord-de-la-france","tag-tapisseries-des-flandres","tag-tenieres","tag-teniers"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lille : terre de femmes et de haute tapisserie - FineLife.tv<\/title>\n<meta name=\"description\" content=\"Lille : terre de femmes et de haute tapisserie. Tr\u00e9sors de laine et de soie au mus\u00e9e de l&#039;Hospice Comtesse pr\u00e9sente pour la premi\u00e8re fois 11 tapisseries, monumentales et m\u00e9connues, de la manufacture Guillaume Werniers &amp; Catherine Ghuys\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lille : terre de femmes et de haute tapisserie - FineLife.tv\" \/>\n<meta property=\"og:description\" content=\"Lille : terre de femmes et de haute tapisserie. Tr\u00e9sors de laine et de soie au mus\u00e9e de l&#039;Hospice Comtesse pr\u00e9sente pour la premi\u00e8re fois 11 tapisseries, monumentales et m\u00e9connues, de la manufacture Guillaume Werniers &amp; Catherine Ghuys\" \/>\n<meta property=\"og:url\" content=\"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/\" \/>\n<meta property=\"og:site_name\" content=\"FineLife.tv\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-08T18:02:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T08:40:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@finelifetv\" \/>\n<meta name=\"twitter:site\" content=\"@finelifetv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/\"},\"author\":{\"name\":\"Leonore\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#\\\/schema\\\/person\\\/e3d980b0c0b3dc5af01c3455893c8c52\"},\"headline\":\"Lille : terre de femmes et de haute tapisserie\",\"datePublished\":\"2026-05-08T18:02:43+00:00\",\"dateModified\":\"2026-05-09T08:40:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/\"},\"wordCount\":1793,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-768x1024.jpeg\",\"keywords\":[\"catherine ghuys\",\"exposition hospice comtesse\",\"exposition tresirs de laine et de soie\",\"guillaume werniers\",\"haute lisse\",\"haute tapisserie\",\"hospice comtesse\",\"jeanne de flandres\",\"lille\",\"manufacture wernieers catherine ghuys\",\"manufactures du Nord de la france\",\"matrimoine\",\"scene champetres\",\"scenes de genre\",\"tapisserie du nord de la france\",\"tapisseries des flandres\",\"teni\u00e8res\",\"teniers\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/\",\"url\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/\",\"name\":\"Lille : terre de femmes et de haute tapisserie - FineLife.tv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-768x1024.jpeg\",\"datePublished\":\"2026-05-08T18:02:43+00:00\",\"dateModified\":\"2026-05-09T08:40:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#\\\/schema\\\/person\\\/e3d980b0c0b3dc5af01c3455893c8c52\"},\"description\":\"Lille : terre de femmes et de haute tapisserie. Tr\u00e9sors de laine et de soie au mus\u00e9e de l'Hospice Comtesse pr\u00e9sente pour la premi\u00e8re fois 11 tapisseries, monumentales et m\u00e9connues, de la manufacture Guillaume Werniers & Catherine Ghuys\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-scaled.jpeg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/05\\\/08\\\/lille-terre-de-femmes-et-de-haute-tapisserie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lille : terre de femmes et de haute tapisserie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/\",\"name\":\"FineLife.tv\",\"description\":\"Quand l&#039;Art de vivre croise l&#039;Art de penser\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#\\\/schema\\\/person\\\/e3d980b0c0b3dc5af01c3455893c8c52\",\"name\":\"Leonore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g\",\"caption\":\"Leonore\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lille : terre de femmes et de haute tapisserie - FineLife.tv","description":"Lille : terre de femmes et de haute tapisserie. Tr\u00e9sors de laine et de soie au mus\u00e9e de l'Hospice Comtesse pr\u00e9sente pour la premi\u00e8re fois 11 tapisseries, monumentales et m\u00e9connues, de la manufacture Guillaume Werniers & Catherine Ghuys","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/","og_locale":"fr_FR","og_type":"article","og_title":"Lille : terre de femmes et de haute tapisserie - FineLife.tv","og_description":"Lille : terre de femmes et de haute tapisserie. Tr\u00e9sors de laine et de soie au mus\u00e9e de l'Hospice Comtesse pr\u00e9sente pour la premi\u00e8re fois 11 tapisseries, monumentales et m\u00e9connues, de la manufacture Guillaume Werniers & Catherine Ghuys","og_url":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/","og_site_name":"FineLife.tv","article_published_time":"2026-05-08T18:02:43+00:00","article_modified_time":"2026-05-09T08:40:48+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-scaled.jpeg","type":"image\/jpeg"}],"author":"Leonore","twitter_card":"summary_large_image","twitter_creator":"@finelifetv","twitter_site":"@finelifetv","twitter_misc":{"\u00c9crit par":"Leonore","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/#article","isPartOf":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/"},"author":{"name":"Leonore","@id":"https:\/\/finelife.tv\/fr\/#\/schema\/person\/e3d980b0c0b3dc5af01c3455893c8c52"},"headline":"Lille : terre de femmes et de haute tapisserie","datePublished":"2026-05-08T18:02:43+00:00","dateModified":"2026-05-09T08:40:48+00:00","mainEntityOfPage":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/"},"wordCount":1793,"commentCount":0,"image":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/#primaryimage"},"thumbnailUrl":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-768x1024.jpeg","keywords":["catherine ghuys","exposition hospice comtesse","exposition tresirs de laine et de soie","guillaume werniers","haute lisse","haute tapisserie","hospice comtesse","jeanne de flandres","lille","manufacture wernieers catherine ghuys","manufactures du Nord de la france","matrimoine","scene champetres","scenes de genre","tapisserie du nord de la france","tapisseries des flandres","teni\u00e8res","teniers"],"articleSection":["Blog"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/","url":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/","name":"Lille : terre de femmes et de haute tapisserie - FineLife.tv","isPartOf":{"@id":"https:\/\/finelife.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/#primaryimage"},"image":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/#primaryimage"},"thumbnailUrl":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-768x1024.jpeg","datePublished":"2026-05-08T18:02:43+00:00","dateModified":"2026-05-09T08:40:48+00:00","author":{"@id":"https:\/\/finelife.tv\/fr\/#\/schema\/person\/e3d980b0c0b3dc5af01c3455893c8c52"},"description":"Lille : terre de femmes et de haute tapisserie. Tr\u00e9sors de laine et de soie au mus\u00e9e de l'Hospice Comtesse pr\u00e9sente pour la premi\u00e8re fois 11 tapisseries, monumentales et m\u00e9connues, de la manufacture Guillaume Werniers & Catherine Ghuys","breadcrumb":{"@id":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/#primaryimage","url":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-scaled.jpeg","contentUrl":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/05\/img-src22https-finelife.tvimage.jpeg22-alt22Lille-terre-de-femmes-et-de-haute-tapisserie22-scaled.jpeg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/finelife.tv\/fr\/2026\/05\/08\/lille-terre-de-femmes-et-de-haute-tapisserie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/finelife.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"Lille : terre de femmes et de haute tapisserie"}]},{"@type":"WebSite","@id":"https:\/\/finelife.tv\/fr\/#website","url":"https:\/\/finelife.tv\/fr\/","name":"FineLife.tv","description":"Quand l&#039;Art de vivre croise l&#039;Art de penser","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/finelife.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/finelife.tv\/fr\/#\/schema\/person\/e3d980b0c0b3dc5af01c3455893c8c52","name":"Leonore","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g","caption":"Leonore"}}]}},"_links":{"self":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts\/28638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/comments?post=28638"}],"version-history":[{"count":62,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts\/28638\/revisions"}],"predecessor-version":[{"id":28725,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts\/28638\/revisions\/28725"}],"wp:attachment":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/media?parent=28638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/categories?post=28638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/tags?post=28638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}