{"id":30354,"date":"2026-07-13T19:49:45","date_gmt":"2026-07-13T17:49:45","guid":{"rendered":"https:\/\/finelife.tv\/fr\/?p=30354"},"modified":"2026-07-15T15:02:45","modified_gmt":"2026-07-15T13:02:45","slug":"canicule-3-delices-fraicheur-pour-se-faire-du-bien","status":"publish","type":"post","link":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/","title":{"rendered":"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"771\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-771x1024.jpg\" alt=\"\" class=\"wp-image-30382\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-771x1024.jpg 771w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-226x300.jpg 226w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-768x1021.jpg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-1156x1536.jpg 1156w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-1541x2048.jpg 1541w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-scaled.jpg 1926w\" sizes=\"auto, (max-width: 771px) 100vw, 771px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><strong>Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien. Il fait chaud, tr\u00e8s chaud, et les \u00e9pisodes de canicule se multiplient. Il y a bien s\u00fbr les recommandations basiques : s\u2019hydrater, privil\u00e9gier les lieux ombrag\u00e9s, \u00e9viter les efforts aux heures les plus chaudes. Mais il y a aussi les petites tips qui font du bien, au corps comme au moral. Voici quelques id\u00e9es simples pour se rafra\u00eechir sans sacrifier le plaisir et sans forc\u00e9ment c\u00e9der au sucre.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Revisiter les c\u00e9r\u00e9ales<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"752\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-cereales-lavoine22.png\" alt=\"\" class=\"wp-image-30379\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-cereales-lavoine22.png 661w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-cereales-lavoine22-264x300.png 264w\" sizes=\"auto, (max-width: 661px) 100vw, 661px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Quand il fait tr\u00e8s chaud, on mange moins. Erreur bien s\u00fbr.  C\u2019est \u00e9videmment le moment de privil\u00e9gier les aliments gorg\u00e9s d\u2019eau : melon, past\u00e8que, concombre, et globalement tous les fruits et l\u00e9gumes de saison. Mais, il faut les associer \u00e0 quelque chose d\u2019un peu plus consistant, comme des l\u00e9gumineuses ou des c\u00e9r\u00e9ales, pour conserver une alimentation \u00e9quilibr\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avez-vous pens\u00e9, par exemple, \u00e0 d\u00e9tourner l\u2019avoine du petit-d\u00e9jeuner? Fond\u00e9e par Gergana Ivanova apr\u00e8s un cursus en nutrith\u00e9rapie, la petite marque fran\u00e7aise <strong><a href=\"https:\/\/lavoine.co\/?srsltid=AfmBOoozf4UCFF6r4Gzw46smqMkJ-CIR8jINod5RWy6kt9xhEmvBD1Xx\">Lavoine<\/a><\/strong> propose des m\u00e9langes app\u00e9tissants (cacao cru, noisettes, graines ou encore pommes s\u00e9ch\u00e9es et cannelle). Sans sucres ajout\u00e9s, riches en fibres et en nutriments, ils sont pens\u00e9s pour se pr\u00e9parer aussi bien chauds que froids. L\u2019id\u00e9e n\u2019est pas propre \u00e0 Lavoine. On trouve en effet ce type de recettes overnight oats un peu partout. On retient toutefois la formule simple et facile \u00e0 reproduire soi-m\u00eame. <br>Dans un bol ou un bocal, m\u00e9langez des flocons d\u2019avoine avec 100 \u00e0 120 ml de lait (ou boisson v\u00e9g\u00e9tale), laissez poser toute la nuit au frigo. Le lendemain, garnissez selon l\u2019envie : fruits frais, graines, un peu de miel ou de pur\u00e9e d\u2019ol\u00e9agineux. Deux minutes de pr\u00e9paration, et un petit-d\u00e9jeuner ou go\u00fbter frais tout pr\u00eat pour les heures chaudes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Le plaisir d\u2019une glace <\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"837\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-glaces-popelino22-837x1024.png\" alt=\"\" class=\"wp-image-30380\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-glaces-popelino22-837x1024.png 837w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-glaces-popelino22-245x300.png 245w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-glaces-popelino22-768x939.png 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-glaces-popelino22.png 1169w\" sizes=\"auto, (max-width: 837px) 100vw, 837px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Pour se rafra\u00eechir, il y a les incontournables, les glaces, aux parfums parfois surprenants, comme l&rsquo;huile d\u2019olive. Les sorbets, restent ind\u00e9niablement l\u2019option la plus l\u00e9g\u00e8re.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En mode Dolce Vita ? Tournez-vous vers des associations plus travaill\u00e9es, comme celles de <strong><a href=\"https:\/\/popelino.fr\/\">Popelino<\/a><\/strong> (Alfagel), une marque franco-italienne qui joue la carte du savoir faire artisanal. Les nouveaut\u00e9s? Des accords noisettes du Pi\u00e9mont \/ cacao qui claque en bouche et citron de Sicile \/ chocolat blanc. Par cette chaleur, ce m\u00e9lange du citron de Sicile acidul\u00e9 et du chocolat gourmand est imbattable. \u00c0 moins de jouer le combo b\u00e2tonnet pistache de Sicile et sa coque de chocolat blanc&#8230; pistache. Mamamia quelle gelaterie !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019essentiel restant de choisir une glace ou un sorbet avec une liste d\u2019ingr\u00e9dients courte et lisible. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un mocktail pour les soir\u00e9es d\u2019\u00e9t\u00e9<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-mocktail22-683x1024.jpg\" alt=\"\" class=\"wp-image-30381\" srcset=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-mocktail22-683x1024.jpg 683w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-mocktail22-200x300.jpg 200w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-mocktail22-768x1152.jpg 768w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-mocktail22-1024x1536.jpg 1024w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-mocktail22-1365x2048.jpg 1365w, https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien-mocktail22-scaled.jpg 1707w\" sizes=\"auto, (max-width: 683px) 100vw, 683px\" \/><figcaption class=\"wp-element-caption\">Cr\u00e9dit photo Unpslash &#8211; Vinn Koonyosyng<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Impossible d\u2019y \u00e9chapper : chaque \u00e9t\u00e9, on cherche de nouvelles boissons fra\u00eeches et d\u00e9salt\u00e9rantes, sans alcool ni sirop trop sucr\u00e9. Acidit\u00e9 franche, bulles, un peu d\u2019amertume, et des herbes aromatiques (menthe, basilic) remplacent le sirop.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Difficile de choisir sa team.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le kombucha et les infusions de fleurs comme l\u2019hibiscus s\u2019imposent aussi comme piliers de l\u2019ap\u00e9ro sans alcool, pour leur l\u00e9g\u00e8re acidit\u00e9 et leur c\u00f4t\u00e9 p\u00e9tillant naturel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f4t\u00e9 saveurs, citron vert, pamplemousse, past\u00e8que et gingembre frais reviennent partout, avec une pr\u00e9f\u00e9rence marqu\u00e9e pour des recettes moins sucr\u00e9es et plus \u201clisibles\u201d qu\u2019avant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Voici une recette simple, inspir\u00e9e d\u2019un mocktail d\u00e9gust\u00e9 en garden party, qui coche plusieurs de ces cases (fruits, acidit\u00e9, bulles) : le litchi-menthe-fraise. Attention aux addictions \ud83d\ude42<br>Pour 4 verres :<br>\u2022 8 litchis (frais ou au sirop), d\u00e9noyaut\u00e9s<br>\u2022 6 fraises bien m\u00fbres<br>\u2022 8 \u00e0 10 feuilles de menthe fra\u00eeche<br>\u2022 1 filet de jus de citron vert<br>\u2022 50 cl de vin mousseux sans alcool bien frais<br>\u2022 Gla\u00e7ons<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pour aller plus loin : repenser sa relation au sucre<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Envie d&rsquo;aller plus loin sur la question du sucre, au-del\u00e0 de la canicule ? Le livre \u201cSucre : dites adieu \u00e0 son emprise\u201d (Dr Cyril Laporte, canc\u00e9rologue, et Pierre Joyeau, micro-nutritionniste) propose une approche int\u00e9ressante : associer la question du sucre \u00e0 des recettes concr\u00e8tes, gourmandes et d\u00e9salt\u00e9rantes, \u00e0 des comportements d\u00e9construits plut\u00f4t \u00e0 qu\u2019\u00e0 une simple liste d\u2019interdits.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sucre : dites adieu \u00e0 son emprise<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">16,99 euros<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c9ditions Mango<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Photo d&rsquo;ouverture : cr\u00e9dit Hongjin-Wang &#8211; Unsplash <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Article li\u00e9 \u00e0 <strong>Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/finelife.tv\/fr\/2025\/12\/29\/5-mocktails-stars-pour-briller-pendant-les-fetes\/\">5 Mocktails stars pour briller pendant les f\u00eates<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/finelife.tv\/fr\/2026\/07\/15\/garden-party-5-idees-pour-lete\/\">Garden party 5 id\u00e9es pour l\u2019\u00e9t\u00e9<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Canicule : 3 pauses fra\u00eecheur pour se faire du bien entre glaces citron Sicile, mocktails litchi-menthe et c\u00e9r\u00e9ales overnights. Choisissez toutes les teams !<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[4214,6377,6381,6372,6374,6380,572,6373,6376,6379,5726,6378],"class_list":["post-30354","post","type-post","status-publish","format-standard","hentry","category-blog","tag-alimentation","tag-avoine","tag-bien-etre-3","tag-canicule","tag-cereales","tag-editions-mangos","tag-fooding","tag-glaces","tag-lavoine","tag-livre-sucre","tag-mocktails","tag-popelino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bienCanicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien - FineLife.tv<\/title>\n<meta name=\"description\" content=\"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien entre glaces citron Sicile, mocktails litchi et c\u00e9r\u00e9ales overnights\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bienCanicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien - FineLife.tv\" \/>\n<meta property=\"og:description\" content=\"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien entre glaces citron Sicile, mocktails litchi et c\u00e9r\u00e9ales overnights\" \/>\n<meta property=\"og:url\" content=\"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/\" \/>\n<meta property=\"og:site_name\" content=\"FineLife.tv\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-13T17:49:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T13:02:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1926\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Leonore\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@finelifetv\" \/>\n<meta name=\"twitter:site\" content=\"@finelifetv\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leonore\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/\"},\"author\":{\"name\":\"Leonore\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#\\\/schema\\\/person\\\/e3d980b0c0b3dc5af01c3455893c8c52\"},\"headline\":\"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien\",\"datePublished\":\"2026-07-13T17:49:45+00:00\",\"dateModified\":\"2026-07-15T13:02:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/\"},\"wordCount\":780,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-771x1024.jpg\",\"keywords\":[\"alimentation\",\"avoine\",\"bien \u00eatre\",\"canicule\",\"c\u00e9reales\",\"editions mangos\",\"fooding\",\"glaces\",\"Lavoine\",\"livre sucre\",\"mocktails\",\"popelino\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/\",\"url\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/\",\"name\":\"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bienCanicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien - FineLife.tv\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-771x1024.jpg\",\"datePublished\":\"2026-07-13T17:49:45+00:00\",\"dateModified\":\"2026-07-15T13:02:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#\\\/schema\\\/person\\\/e3d980b0c0b3dc5af01c3455893c8c52\"},\"description\":\"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien entre glaces citron Sicile, mocktails litchi et c\u00e9r\u00e9ales overnights\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-scaled.jpg\",\"width\":1926,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/2026\\\/07\\\/13\\\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/\",\"name\":\"FineLife.tv\",\"description\":\"Quand l&#039;Art de vivre croise l&#039;Art de penser\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/finelife.tv\\\/fr\\\/#\\\/schema\\\/person\\\/e3d980b0c0b3dc5af01c3455893c8c52\",\"name\":\"Leonore\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g\",\"caption\":\"Leonore\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bienCanicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien - FineLife.tv","description":"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien entre glaces citron Sicile, mocktails litchi et c\u00e9r\u00e9ales overnights","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/","og_locale":"fr_FR","og_type":"article","og_title":"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bienCanicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien - FineLife.tv","og_description":"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien entre glaces citron Sicile, mocktails litchi et c\u00e9r\u00e9ales overnights","og_url":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/","og_site_name":"FineLife.tv","article_published_time":"2026-07-13T17:49:45+00:00","article_modified_time":"2026-07-15T13:02:45+00:00","og_image":[{"width":1926,"height":2560,"url":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-scaled.jpg","type":"image\/jpeg"}],"author":"Leonore","twitter_card":"summary_large_image","twitter_creator":"@finelifetv","twitter_site":"@finelifetv","twitter_misc":{"\u00c9crit par":"Leonore","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/#article","isPartOf":{"@id":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/"},"author":{"name":"Leonore","@id":"https:\/\/finelife.tv\/fr\/#\/schema\/person\/e3d980b0c0b3dc5af01c3455893c8c52"},"headline":"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien","datePublished":"2026-07-13T17:49:45+00:00","dateModified":"2026-07-15T13:02:45+00:00","mainEntityOfPage":{"@id":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/"},"wordCount":780,"commentCount":0,"image":{"@id":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/#primaryimage"},"thumbnailUrl":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-771x1024.jpg","keywords":["alimentation","avoine","bien \u00eatre","canicule","c\u00e9reales","editions mangos","fooding","glaces","Lavoine","livre sucre","mocktails","popelino"],"articleSection":["Blog"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/","url":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/","name":"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bienCanicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien - FineLife.tv","isPartOf":{"@id":"https:\/\/finelife.tv\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/#primaryimage"},"image":{"@id":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/#primaryimage"},"thumbnailUrl":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-771x1024.jpg","datePublished":"2026-07-13T17:49:45+00:00","dateModified":"2026-07-15T13:02:45+00:00","author":{"@id":"https:\/\/finelife.tv\/fr\/#\/schema\/person\/e3d980b0c0b3dc5af01c3455893c8c52"},"description":"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien entre glaces citron Sicile, mocktails litchi et c\u00e9r\u00e9ales overnights","breadcrumb":{"@id":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/#primaryimage","url":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-scaled.jpg","contentUrl":"https:\/\/finelife.tv\/fr\/wp-content\/uploads\/2026\/07\/img-src22https-finelife.tvimage.jpeg22-alt22Canicule-3-delices-fraicheur-pour-se-faire-du-bien22-scaled.jpg","width":1926,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/finelife.tv\/fr\/2026\/07\/13\/canicule-3-delices-fraicheur-pour-se-faire-du-bien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/finelife.tv\/fr\/"},{"@type":"ListItem","position":2,"name":"Canicule : 3 d\u00e9lices fra\u00eecheur pour se faire du bien"}]},{"@type":"WebSite","@id":"https:\/\/finelife.tv\/fr\/#website","url":"https:\/\/finelife.tv\/fr\/","name":"FineLife.tv","description":"Quand l&#039;Art de vivre croise l&#039;Art de penser","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/finelife.tv\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/finelife.tv\/fr\/#\/schema\/person\/e3d980b0c0b3dc5af01c3455893c8c52","name":"Leonore","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9a2e5073417479f910ffdeee54da5ccf4f91eab62746ce0ae0e81124a9491a79?s=96&d=mm&r=g","caption":"Leonore"}}]}},"_links":{"self":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts\/30354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/comments?post=30354"}],"version-history":[{"count":37,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts\/30354\/revisions"}],"predecessor-version":[{"id":30477,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/posts\/30354\/revisions\/30477"}],"wp:attachment":[{"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/media?parent=30354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/categories?post=30354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/finelife.tv\/fr\/wp-json\/wp\/v2\/tags?post=30354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}